{"id":869,"count":1,"description":"","link":"https:\/\/doinamerica.com\/de\/etikett\/master-honduras-stipendien-fur-ingenieurwissenschaften-absolventen-mit-diesem-einfachen\/","name":"Master Honduras Stipendien f\u00fcr Ingenieur- und Naturwissenschaftsabsolventen mit diesem einfachen","slug":"master-honduras-stipendien-fur-ingenieurwissenschaften-absolventen-mit-diesem-einfachen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/doinamerica.com\/de\/wp-json\/wp\/v2\/tags\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doinamerica.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/doinamerica.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/doinamerica.com\/de\/wp-json\/wp\/v2\/posts?tags=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}